{"id":34468,"date":"2023-08-23T17:00:12","date_gmt":"2023-08-23T20:00:12","guid":{"rendered":"https:\/\/www.vagasempregosc.com.br\/?p=34468"},"modified":"2023-08-23T17:00:12","modified_gmt":"2023-08-23T20:00:12","slug":"codigo-24298-assistente-de-desenvolvimento-de-produto-blumenau-sc","status":"publish","type":"post","link":"https:\/\/www.vagasempregosc.com.br\/index.php\/2023\/08\/23\/codigo-24298-assistente-de-desenvolvimento-de-produto-blumenau-sc\/","title":{"rendered":"C\u00f3digo: 24298  &#8211; Assistente de Desenvolvimento de Produto &#8211; Blumenau &#8211; SC"},"content":{"rendered":"<p style=\"text-align: justify;\">Requisitos:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Ensino Superior Cursando Moda, Engenharia T\u00eaxtil ou \u00e1reas afins.<\/li>\n<li>Conhecimento b\u00e1sico em modelagem, engenharia de produto, desenvolvimento de produto t\u00eaxtil, mat\u00e9ria prima (tecidos e aviamentos) e processos de confec\u00e7\u00e3o. Dom\u00ednio com as ferramentas de TI (Pacote Office, CorelDraw, Word, Excel, Power Point).<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Atividades da fun\u00e7\u00e3o:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Desenvolver produtos a partir das diretrizes da cole\u00e7\u00e3o fornecidas pelo departamento de Estilo, assegurando assertividade no visual do produto, modelagem, viabilidade t\u00e9cnica e qualidade, para entregar o produto adequado ao consumidor final, no prazo das cole\u00e7\u00f5es e pre\u00e7o acess\u00edvel. Analisar, cadastrar e garantir a qualidade da informa\u00e7\u00e3o na ficha t\u00e9cnica. Acompanhar e fazer provas de modelagem, registrando os coment\u00e1rios na ficha de verifica\u00e7\u00e3o com as fotos. Monitorar e cobrar recebimento das pe\u00e7as de prot\u00f3tipo com os fornecedores. Controlar os artigos sob sua responsabilidade, cuidando do desenvolvimento da fase de briefing at\u00e9 entrega final. Garantir o processo de desenvolvimento de cole\u00e7\u00e3o no prazo previsto em cronograma. Contribuir para viabilizar as metas da \u00e1rea, utilizando ferramentas de controle no sistema e planilhas.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Descri\u00e7\u00e3o:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Oportunidade tempor\u00e1ria<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Jornada de Trabalho:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Segunda a Sexta Feira das 08:00 \u00e0s 17:30<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Benef\u00edcios:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Vale transporte e refeit\u00f3rio na empresa.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Enviar curr\u00edculo informando no assunto do e-mail a vaga de interesse para o Link recrutarrh.com.br<br \/>\nMaiores informa\u00e7\u00f5es pelo fone (47) 3222-0102 \/ Vaga: 24298<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Requisitos: Ensino Superior Cursando Moda, Engenharia T\u00eaxtil ou \u00e1reas afins. Conhecimento b\u00e1sico em modelagem, engenharia de produto, desenvolvimento de produto t\u00eaxtil, mat\u00e9ria prima (tecidos e [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,16,45],"tags":[],"class_list":["post-34468","post","type-post","status-publish","format-standard","hentry","category-ensino-superior-em-andamento-incompleto","category-industria-textil-moda","category-trabalho-temporario"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f3digo: 24298 - Assistente de Desenvolvimento de Produto - Blumenau - SC - Vagas Emprego SC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vagasempregosc.com.br\/index.php\/2023\/08\/23\/codigo-24298-assistente-de-desenvolvimento-de-produto-blumenau-sc\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3digo: 24298 - Assistente de Desenvolvimento de Produto - Blumenau - SC - Vagas Emprego SC\" \/>\n<meta property=\"og:description\" content=\"Requisitos: Ensino Superior Cursando Moda, Engenharia T\u00eaxtil ou \u00e1reas afins. Conhecimento b\u00e1sico em modelagem, engenharia de produto, desenvolvimento de produto t\u00eaxtil, mat\u00e9ria prima (tecidos e [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vagasempregosc.com.br\/index.php\/2023\/08\/23\/codigo-24298-assistente-de-desenvolvimento-de-produto-blumenau-sc\/\" \/>\n<meta property=\"og:site_name\" content=\"Vagas Emprego SC\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-23T20:00:12+00:00\" \/>\n<meta name=\"author\" content=\"Vagas Emprego SC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vagas Emprego SC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2023\\\/08\\\/23\\\/codigo-24298-assistente-de-desenvolvimento-de-produto-blumenau-sc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2023\\\/08\\\/23\\\/codigo-24298-assistente-de-desenvolvimento-de-produto-blumenau-sc\\\/\"},\"author\":{\"name\":\"Vagas Emprego SC\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#\\\/schema\\\/person\\\/e59ecb0cf33cc401d3b82548d1a9baa4\"},\"headline\":\"C\u00f3digo: 24298 &#8211; Assistente de Desenvolvimento de Produto &#8211; Blumenau &#8211; SC\",\"datePublished\":\"2023-08-23T20:00:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2023\\\/08\\\/23\\\/codigo-24298-assistente-de-desenvolvimento-de-produto-blumenau-sc\\\/\"},\"wordCount\":245,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#organization\"},\"articleSection\":[\"ensino superior incompleto\",\"ind\u00fastria t\u00eaxtil \\\/ moda\",\"trabalho tempor\u00e1rio\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2023\\\/08\\\/23\\\/codigo-24298-assistente-de-desenvolvimento-de-produto-blumenau-sc\\\/\",\"url\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2023\\\/08\\\/23\\\/codigo-24298-assistente-de-desenvolvimento-de-produto-blumenau-sc\\\/\",\"name\":\"C\u00f3digo: 24298 - Assistente de Desenvolvimento de Produto - Blumenau - SC - Vagas Emprego SC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#website\"},\"datePublished\":\"2023-08-23T20:00:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2023\\\/08\\\/23\\\/codigo-24298-assistente-de-desenvolvimento-de-produto-blumenau-sc\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2023\\\/08\\\/23\\\/codigo-24298-assistente-de-desenvolvimento-de-produto-blumenau-sc\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2023\\\/08\\\/23\\\/codigo-24298-assistente-de-desenvolvimento-de-produto-blumenau-sc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3digo: 24298 &#8211; Assistente de Desenvolvimento de Produto &#8211; Blumenau &#8211; SC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#website\",\"url\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/\",\"name\":\"Vagas Emprego SC\",\"description\":\"Vagas de emprego e est\u00e1gio em Santa Catarina\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#organization\",\"name\":\"Vagas Emprego SC\",\"url\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-logo2015sc.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-logo2015sc.jpg\",\"width\":323,\"height\":89,\"caption\":\"Vagas Emprego SC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#\\\/schema\\\/person\\\/e59ecb0cf33cc401d3b82548d1a9baa4\",\"name\":\"Vagas Emprego SC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"caption\":\"Vagas Emprego SC\"},\"url\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/author\\\/vagasemprego\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3digo: 24298 - Assistente de Desenvolvimento de Produto - Blumenau - SC - Vagas Emprego SC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vagasempregosc.com.br\/index.php\/2023\/08\/23\/codigo-24298-assistente-de-desenvolvimento-de-produto-blumenau-sc\/","og_locale":"pt_BR","og_type":"article","og_title":"C\u00f3digo: 24298 - Assistente de Desenvolvimento de Produto - Blumenau - SC - Vagas Emprego SC","og_description":"Requisitos: Ensino Superior Cursando Moda, Engenharia T\u00eaxtil ou \u00e1reas afins. Conhecimento b\u00e1sico em modelagem, engenharia de produto, desenvolvimento de produto t\u00eaxtil, mat\u00e9ria prima (tecidos e [...]","og_url":"https:\/\/www.vagasempregosc.com.br\/index.php\/2023\/08\/23\/codigo-24298-assistente-de-desenvolvimento-de-produto-blumenau-sc\/","og_site_name":"Vagas Emprego SC","article_published_time":"2023-08-23T20:00:12+00:00","author":"Vagas Emprego SC","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Vagas Emprego SC","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vagasempregosc.com.br\/index.php\/2023\/08\/23\/codigo-24298-assistente-de-desenvolvimento-de-produto-blumenau-sc\/#article","isPartOf":{"@id":"https:\/\/www.vagasempregosc.com.br\/index.php\/2023\/08\/23\/codigo-24298-assistente-de-desenvolvimento-de-produto-blumenau-sc\/"},"author":{"name":"Vagas Emprego SC","@id":"https:\/\/www.vagasempregosc.com.br\/#\/schema\/person\/e59ecb0cf33cc401d3b82548d1a9baa4"},"headline":"C\u00f3digo: 24298 &#8211; Assistente de Desenvolvimento de Produto &#8211; Blumenau &#8211; SC","datePublished":"2023-08-23T20:00:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vagasempregosc.com.br\/index.php\/2023\/08\/23\/codigo-24298-assistente-de-desenvolvimento-de-produto-blumenau-sc\/"},"wordCount":245,"publisher":{"@id":"https:\/\/www.vagasempregosc.com.br\/#organization"},"articleSection":["ensino superior incompleto","ind\u00fastria t\u00eaxtil \/ moda","trabalho tempor\u00e1rio"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.vagasempregosc.com.br\/index.php\/2023\/08\/23\/codigo-24298-assistente-de-desenvolvimento-de-produto-blumenau-sc\/","url":"https:\/\/www.vagasempregosc.com.br\/index.php\/2023\/08\/23\/codigo-24298-assistente-de-desenvolvimento-de-produto-blumenau-sc\/","name":"C\u00f3digo: 24298 - Assistente de Desenvolvimento de Produto - Blumenau - SC - Vagas Emprego SC","isPartOf":{"@id":"https:\/\/www.vagasempregosc.com.br\/#website"},"datePublished":"2023-08-23T20:00:12+00:00","breadcrumb":{"@id":"https:\/\/www.vagasempregosc.com.br\/index.php\/2023\/08\/23\/codigo-24298-assistente-de-desenvolvimento-de-produto-blumenau-sc\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vagasempregosc.com.br\/index.php\/2023\/08\/23\/codigo-24298-assistente-de-desenvolvimento-de-produto-blumenau-sc\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vagasempregosc.com.br\/index.php\/2023\/08\/23\/codigo-24298-assistente-de-desenvolvimento-de-produto-blumenau-sc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vagasempregosc.com.br\/"},{"@type":"ListItem","position":2,"name":"C\u00f3digo: 24298 &#8211; Assistente de Desenvolvimento de Produto &#8211; Blumenau &#8211; SC"}]},{"@type":"WebSite","@id":"https:\/\/www.vagasempregosc.com.br\/#website","url":"https:\/\/www.vagasempregosc.com.br\/","name":"Vagas Emprego SC","description":"Vagas de emprego e est\u00e1gio em Santa Catarina","publisher":{"@id":"https:\/\/www.vagasempregosc.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vagasempregosc.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.vagasempregosc.com.br\/#organization","name":"Vagas Emprego SC","url":"https:\/\/www.vagasempregosc.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.vagasempregosc.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.vagasempregosc.com.br\/wp-content\/uploads\/2025\/05\/cropped-logo2015sc.jpg","contentUrl":"https:\/\/www.vagasempregosc.com.br\/wp-content\/uploads\/2025\/05\/cropped-logo2015sc.jpg","width":323,"height":89,"caption":"Vagas Emprego SC"},"image":{"@id":"https:\/\/www.vagasempregosc.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.vagasempregosc.com.br\/#\/schema\/person\/e59ecb0cf33cc401d3b82548d1a9baa4","name":"Vagas Emprego SC","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","caption":"Vagas Emprego SC"},"url":"https:\/\/www.vagasempregosc.com.br\/index.php\/author\/vagasemprego\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/34468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=34468"}],"version-history":[{"count":0,"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/34468\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=34468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=34468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=34468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}