{"id":36626,"date":"2024-02-28T11:00:02","date_gmt":"2024-02-28T14:00:02","guid":{"rendered":"https:\/\/www.vagasempregosc.com.br\/?p=36626"},"modified":"2024-02-28T11:00:02","modified_gmt":"2024-02-28T14:00:02","slug":"codigo-25050-ajudante-de-maquina-de-colagem-blumenau-sc-2","status":"publish","type":"post","link":"https:\/\/www.vagasempregosc.com.br\/index.php\/2024\/02\/28\/codigo-25050-ajudante-de-maquina-de-colagem-blumenau-sc-2\/","title":{"rendered":"C\u00f3digo: 25050  &#8211;  Ajudante de M\u00e1quina de Colagem &#8211; Blumenau &#8211; SC"},"content":{"rendered":"<p style=\"text-align: justify;\">Requisitos:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Ensino Fundamental (m\u00ednimo 6\u00aa s\u00e9rie)<\/li>\n<li>Ter conhecimento na \u00e1rea produtiva.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Atividades da fun\u00e7\u00e3o:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Alimentar a m\u00e1quina com embalagens, auxiliar o operador no preparo da m\u00e1quina com abastecimento de cola e ajustes. Apanhar embalagens na sa\u00edda da m\u00e1quina de colagem e transportar pilhas de papel e cart\u00e3o para outros setores.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Descri\u00e7\u00e3o:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Oportunidade tempor\u00e1ria<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Jornada de trabalho:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Segunda a Sexta Feira das 13:30 \u00e0s 22:00 e S\u00e1bado das 09:00 \u00e0s 13:00<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Benef\u00edcios:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Vale transporte, refeit\u00f3rio pr\u00f3prio e 5% de assiduidade.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Enviar curr\u00edculo informando no assunto do e-mail a vaga de interesse para o Link recrutarrh.com.br<br \/>\nMaiores informa\u00e7\u00f5es pelo fone (47) 3222-0102 \/ Vaga: 24017<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Requisitos: Ensino Fundamental (m\u00ednimo 6\u00aa s\u00e9rie) Ter conhecimento na \u00e1rea produtiva. Atividades da fun\u00e7\u00e3o: Alimentar a m\u00e1quina com embalagens, auxiliar o operador no preparo da [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,3,45],"tags":[],"class_list":["post-36626","post","type-post","status-publish","format-standard","hentry","category-ensino-fundamental-completo","category-industria-producao","category-trabalho-temporario"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f3digo: 25050 - Ajudante de M\u00e1quina de Colagem - Blumenau - SC - Vagas Emprego SC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vagasempregosc.com.br\/index.php\/2024\/02\/28\/codigo-25050-ajudante-de-maquina-de-colagem-blumenau-sc-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3digo: 25050 - Ajudante de M\u00e1quina de Colagem - Blumenau - SC - Vagas Emprego SC\" \/>\n<meta property=\"og:description\" content=\"Requisitos: Ensino Fundamental (m\u00ednimo 6\u00aa s\u00e9rie) Ter conhecimento na \u00e1rea produtiva. Atividades da fun\u00e7\u00e3o: Alimentar a m\u00e1quina com embalagens, auxiliar o operador no preparo da [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vagasempregosc.com.br\/index.php\/2024\/02\/28\/codigo-25050-ajudante-de-maquina-de-colagem-blumenau-sc-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Vagas Emprego SC\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-28T14:00:02+00:00\" \/>\n<meta name=\"author\" content=\"Vagas Emprego SC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vagas Emprego SC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2024\\\/02\\\/28\\\/codigo-25050-ajudante-de-maquina-de-colagem-blumenau-sc-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2024\\\/02\\\/28\\\/codigo-25050-ajudante-de-maquina-de-colagem-blumenau-sc-2\\\/\"},\"author\":{\"name\":\"Vagas Emprego SC\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#\\\/schema\\\/person\\\/e59ecb0cf33cc401d3b82548d1a9baa4\"},\"headline\":\"C\u00f3digo: 25050 &#8211; Ajudante de M\u00e1quina de Colagem &#8211; Blumenau &#8211; SC\",\"datePublished\":\"2024-02-28T14:00:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2024\\\/02\\\/28\\\/codigo-25050-ajudante-de-maquina-de-colagem-blumenau-sc-2\\\/\"},\"wordCount\":125,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#organization\"},\"articleSection\":[\"ensino fundamental\",\"ind\u00fastria\",\"trabalho tempor\u00e1rio\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2024\\\/02\\\/28\\\/codigo-25050-ajudante-de-maquina-de-colagem-blumenau-sc-2\\\/\",\"url\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2024\\\/02\\\/28\\\/codigo-25050-ajudante-de-maquina-de-colagem-blumenau-sc-2\\\/\",\"name\":\"C\u00f3digo: 25050 - Ajudante de M\u00e1quina de Colagem - Blumenau - SC - Vagas Emprego SC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#website\"},\"datePublished\":\"2024-02-28T14:00:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2024\\\/02\\\/28\\\/codigo-25050-ajudante-de-maquina-de-colagem-blumenau-sc-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2024\\\/02\\\/28\\\/codigo-25050-ajudante-de-maquina-de-colagem-blumenau-sc-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2024\\\/02\\\/28\\\/codigo-25050-ajudante-de-maquina-de-colagem-blumenau-sc-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3digo: 25050 &#8211; Ajudante de M\u00e1quina de Colagem &#8211; Blumenau &#8211; SC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#website\",\"url\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/\",\"name\":\"Vagas Emprego SC\",\"description\":\"Vagas de emprego e est\u00e1gio em Santa Catarina\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#organization\",\"name\":\"Vagas Emprego SC\",\"url\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-logo2015sc.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-logo2015sc.jpg\",\"width\":323,\"height\":89,\"caption\":\"Vagas Emprego SC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#\\\/schema\\\/person\\\/e59ecb0cf33cc401d3b82548d1a9baa4\",\"name\":\"Vagas Emprego SC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"caption\":\"Vagas Emprego SC\"},\"url\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/author\\\/vagasemprego\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3digo: 25050 - Ajudante de M\u00e1quina de Colagem - Blumenau - SC - Vagas Emprego SC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vagasempregosc.com.br\/index.php\/2024\/02\/28\/codigo-25050-ajudante-de-maquina-de-colagem-blumenau-sc-2\/","og_locale":"pt_BR","og_type":"article","og_title":"C\u00f3digo: 25050 - Ajudante de M\u00e1quina de Colagem - Blumenau - SC - Vagas Emprego SC","og_description":"Requisitos: Ensino Fundamental (m\u00ednimo 6\u00aa s\u00e9rie) Ter conhecimento na \u00e1rea produtiva. Atividades da fun\u00e7\u00e3o: Alimentar a m\u00e1quina com embalagens, auxiliar o operador no preparo da [...]","og_url":"https:\/\/www.vagasempregosc.com.br\/index.php\/2024\/02\/28\/codigo-25050-ajudante-de-maquina-de-colagem-blumenau-sc-2\/","og_site_name":"Vagas Emprego SC","article_published_time":"2024-02-28T14:00:02+00:00","author":"Vagas Emprego SC","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Vagas Emprego SC","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vagasempregosc.com.br\/index.php\/2024\/02\/28\/codigo-25050-ajudante-de-maquina-de-colagem-blumenau-sc-2\/#article","isPartOf":{"@id":"https:\/\/www.vagasempregosc.com.br\/index.php\/2024\/02\/28\/codigo-25050-ajudante-de-maquina-de-colagem-blumenau-sc-2\/"},"author":{"name":"Vagas Emprego SC","@id":"https:\/\/www.vagasempregosc.com.br\/#\/schema\/person\/e59ecb0cf33cc401d3b82548d1a9baa4"},"headline":"C\u00f3digo: 25050 &#8211; Ajudante de M\u00e1quina de Colagem &#8211; Blumenau &#8211; SC","datePublished":"2024-02-28T14:00:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vagasempregosc.com.br\/index.php\/2024\/02\/28\/codigo-25050-ajudante-de-maquina-de-colagem-blumenau-sc-2\/"},"wordCount":125,"publisher":{"@id":"https:\/\/www.vagasempregosc.com.br\/#organization"},"articleSection":["ensino fundamental","ind\u00fastria","trabalho tempor\u00e1rio"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.vagasempregosc.com.br\/index.php\/2024\/02\/28\/codigo-25050-ajudante-de-maquina-de-colagem-blumenau-sc-2\/","url":"https:\/\/www.vagasempregosc.com.br\/index.php\/2024\/02\/28\/codigo-25050-ajudante-de-maquina-de-colagem-blumenau-sc-2\/","name":"C\u00f3digo: 25050 - Ajudante de M\u00e1quina de Colagem - Blumenau - SC - Vagas Emprego SC","isPartOf":{"@id":"https:\/\/www.vagasempregosc.com.br\/#website"},"datePublished":"2024-02-28T14:00:02+00:00","breadcrumb":{"@id":"https:\/\/www.vagasempregosc.com.br\/index.php\/2024\/02\/28\/codigo-25050-ajudante-de-maquina-de-colagem-blumenau-sc-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vagasempregosc.com.br\/index.php\/2024\/02\/28\/codigo-25050-ajudante-de-maquina-de-colagem-blumenau-sc-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vagasempregosc.com.br\/index.php\/2024\/02\/28\/codigo-25050-ajudante-de-maquina-de-colagem-blumenau-sc-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vagasempregosc.com.br\/"},{"@type":"ListItem","position":2,"name":"C\u00f3digo: 25050 &#8211; Ajudante de M\u00e1quina de Colagem &#8211; Blumenau &#8211; SC"}]},{"@type":"WebSite","@id":"https:\/\/www.vagasempregosc.com.br\/#website","url":"https:\/\/www.vagasempregosc.com.br\/","name":"Vagas Emprego SC","description":"Vagas de emprego e est\u00e1gio em Santa Catarina","publisher":{"@id":"https:\/\/www.vagasempregosc.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vagasempregosc.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.vagasempregosc.com.br\/#organization","name":"Vagas Emprego SC","url":"https:\/\/www.vagasempregosc.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.vagasempregosc.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.vagasempregosc.com.br\/wp-content\/uploads\/2025\/05\/cropped-logo2015sc.jpg","contentUrl":"https:\/\/www.vagasempregosc.com.br\/wp-content\/uploads\/2025\/05\/cropped-logo2015sc.jpg","width":323,"height":89,"caption":"Vagas Emprego SC"},"image":{"@id":"https:\/\/www.vagasempregosc.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.vagasempregosc.com.br\/#\/schema\/person\/e59ecb0cf33cc401d3b82548d1a9baa4","name":"Vagas Emprego SC","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","caption":"Vagas Emprego SC"},"url":"https:\/\/www.vagasempregosc.com.br\/index.php\/author\/vagasemprego\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/36626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=36626"}],"version-history":[{"count":0,"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/36626\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=36626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=36626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=36626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}