{"id":39067,"date":"2024-08-13T17:00:41","date_gmt":"2024-08-13T20:00:41","guid":{"rendered":"https:\/\/www.vagasempregosc.com.br\/?p=39067"},"modified":"2024-08-13T17:00:41","modified_gmt":"2024-08-13T20:00:41","slug":"assistente-de-orcamento-palhoca-sc-17","status":"publish","type":"post","link":"https:\/\/www.vagasempregosc.com.br\/index.php\/2024\/08\/13\/assistente-de-orcamento-palhoca-sc-17\/","title":{"rendered":"Assistente de Or\u00e7amento &#8211; Palho\u00e7a &#8211; SC"},"content":{"rendered":"<p style=\"text-align: justify;\">Atribui\u00e7\u00f5es:<br \/>\nDescri\u00e7\u00e3o da vaga:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Procuramos por pessoas que amem um bom atendimento. Profissionais que tenham paix\u00e3o e desejo de entregar a melhor experi\u00eancia para os nossos clientes, fazendo com que cada cliente se sinta \u00fanico e especial. Se voc\u00ea adora trabalhar com o p\u00fablico, \u00e9 boa em resolu\u00e7\u00e3o de problemas, tem empatia e aten\u00e7\u00e3o aos detalhes, venha fazer parte da nossa equipe!<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Responsabilidades e atribui\u00e7\u00f5es:<\/p>\n<ul style=\"text-align: justify;\">\n<li>\u00a0Realizar or\u00e7amentos de receitu\u00e1rios m\u00e9dicos;<\/li>\n<li>\u00a0Conferir or\u00e7amentos j\u00e1 realizados;<\/li>\n<li>\u00a0Efetuar e\/ou conferir cadastros dos nossos clientes.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Requisitos:<br \/>\nRequisitos e qualifica\u00e7\u00f5es:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Ensino m\u00e9dio completo;<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Jornada de Trabalho:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Segunda a Sexta Feira das 09:36 \u00e0s 19:30 e S\u00e1bados por escala das 08:00 as 12:00.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Benef\u00edcios:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Vale Alimenta\u00e7\u00e3o ou Refei\u00e7\u00e3o (sem desconto de 20%);<\/li>\n<li>Vale Transporte ou Vale combust\u00edvel (sem desconto de 6%);<\/li>\n<li>Plano de Sa\u00fade Unimed (mensalidade coberta pela empresa);<\/li>\n<li>Plano Odontol\u00f3gico Uniodonto;<\/li>\n<li>B\u00f4nus de Merecimento;<\/li>\n<li>Seguro de Vida;<\/li>\n<li>Desconto em nossos produtos (Essentia Pharma, Essential Nutrition e Noorskin);<\/li>\n<li>Rede de descontos em lojas, restaurantes e academias;<\/li>\n<li>Presente de final de ano;<\/li>\n<li>\u00c1rea de confraterniza\u00e7\u00e3o com churrasqueira;<\/li>\n<li>Sala de medita\u00e7\u00e3o;<\/li>\n<li>Sala de descanso;<\/li>\n<li>Programa de promo\u00e7\u00e3o \u00e0 sa\u00fade com atendimento m\u00e9dico e pedi\u00e1trico;<\/li>\n<li>Programa de promo\u00e7\u00e3o \u00e0 qualidade de vida com terapeutas, coachings e psic\u00f3logos, incluindo t\u00e9cnicas de mindfulness, wellness e manejo do estresse;<\/li>\n<li>Projeto Be Generous &#8211; suplementa\u00e7\u00e3o para as colaboradoras durante a gesta\u00e7\u00e3o;<\/li>\n<li>Gin\u00e1stica laboral;<\/li>\n<li>Conv\u00eanio com faculdades, cursos de idiomas e escolas educa\u00e7\u00e3o infantil;<\/li>\n<li>Bolsa de Aux\u00edlio Educa\u00e7\u00e3o de at\u00e9 50% do valor do curso;<\/li>\n<li>Curso de Desenvolvimento da Intelig\u00eancia Emocional;<\/li>\n<li>Cursos de capacita\u00e7\u00e3o profissional;<\/li>\n<li>Produtos da linha Essential Nutrition dispon\u00edveis nos refeit\u00f3rios;<\/li>\n<li>Estacionamento gratuito;<\/li>\n<li>Ambiente de trabalho acolhedor &#8211; Cultura Essentia.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Observa\u00e7\u00f5es:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Data m\u00e1xima para envio de curr\u00edculos:\u00a0 12-09-2024<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Enviar curr\u00edculo informando no assunto do e-mail a vaga de interesse para<a href=\"mailto:rh@essentialnutrition.com.br\"> rh@essentialnutrition.com.br<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Atribui\u00e7\u00f5es: Descri\u00e7\u00e3o da vaga: Procuramos por pessoas que amem um bom atendimento. Profissionais que tenham paix\u00e3o e desejo de entregar a melhor experi\u00eancia para os [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2,12],"tags":[],"class_list":["post-39067","post","type-post","status-publish","format-standard","hentry","category-administrativa","category-ensino-medio-completo","category-diversos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Assistente de Or\u00e7amento - Palho\u00e7a - SC - Vagas Emprego SC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vagasempregosc.com.br\/index.php\/2024\/08\/13\/assistente-de-orcamento-palhoca-sc-17\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Assistente de Or\u00e7amento - Palho\u00e7a - SC - Vagas Emprego SC\" \/>\n<meta property=\"og:description\" content=\"Atribui\u00e7\u00f5es: Descri\u00e7\u00e3o da vaga: Procuramos por pessoas que amem um bom atendimento. Profissionais que tenham paix\u00e3o e desejo de entregar a melhor experi\u00eancia para os [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vagasempregosc.com.br\/index.php\/2024\/08\/13\/assistente-de-orcamento-palhoca-sc-17\/\" \/>\n<meta property=\"og:site_name\" content=\"Vagas Emprego SC\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-13T20:00:41+00:00\" \/>\n<meta name=\"author\" content=\"Vagas Emprego SC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vagas Emprego SC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2024\\\/08\\\/13\\\/assistente-de-orcamento-palhoca-sc-17\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2024\\\/08\\\/13\\\/assistente-de-orcamento-palhoca-sc-17\\\/\"},\"author\":{\"name\":\"Vagas Emprego SC\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#\\\/schema\\\/person\\\/e59ecb0cf33cc401d3b82548d1a9baa4\"},\"headline\":\"Assistente de Or\u00e7amento &#8211; Palho\u00e7a &#8211; SC\",\"datePublished\":\"2024-08-13T20:00:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2024\\\/08\\\/13\\\/assistente-de-orcamento-palhoca-sc-17\\\/\"},\"wordCount\":339,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#organization\"},\"articleSection\":[\"administra\u00e7\u00e3o geral\",\"ensino m\u00e9dio\",\"vagas diversas\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2024\\\/08\\\/13\\\/assistente-de-orcamento-palhoca-sc-17\\\/\",\"url\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2024\\\/08\\\/13\\\/assistente-de-orcamento-palhoca-sc-17\\\/\",\"name\":\"Assistente de Or\u00e7amento - Palho\u00e7a - SC - Vagas Emprego SC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#website\"},\"datePublished\":\"2024-08-13T20:00:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2024\\\/08\\\/13\\\/assistente-de-orcamento-palhoca-sc-17\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2024\\\/08\\\/13\\\/assistente-de-orcamento-palhoca-sc-17\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2024\\\/08\\\/13\\\/assistente-de-orcamento-palhoca-sc-17\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Assistente de Or\u00e7amento &#8211; Palho\u00e7a &#8211; SC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#website\",\"url\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/\",\"name\":\"Vagas Emprego SC\",\"description\":\"Vagas de emprego e est\u00e1gio em Santa Catarina\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#organization\",\"name\":\"Vagas Emprego SC\",\"url\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-logo2015sc.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-logo2015sc.jpg\",\"width\":323,\"height\":89,\"caption\":\"Vagas Emprego SC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#\\\/schema\\\/person\\\/e59ecb0cf33cc401d3b82548d1a9baa4\",\"name\":\"Vagas Emprego SC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"caption\":\"Vagas Emprego SC\"},\"url\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/author\\\/vagasemprego\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Assistente de Or\u00e7amento - Palho\u00e7a - SC - Vagas Emprego SC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vagasempregosc.com.br\/index.php\/2024\/08\/13\/assistente-de-orcamento-palhoca-sc-17\/","og_locale":"pt_BR","og_type":"article","og_title":"Assistente de Or\u00e7amento - Palho\u00e7a - SC - Vagas Emprego SC","og_description":"Atribui\u00e7\u00f5es: Descri\u00e7\u00e3o da vaga: Procuramos por pessoas que amem um bom atendimento. Profissionais que tenham paix\u00e3o e desejo de entregar a melhor experi\u00eancia para os [...]","og_url":"https:\/\/www.vagasempregosc.com.br\/index.php\/2024\/08\/13\/assistente-de-orcamento-palhoca-sc-17\/","og_site_name":"Vagas Emprego SC","article_published_time":"2024-08-13T20:00:41+00:00","author":"Vagas Emprego SC","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Vagas Emprego SC","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vagasempregosc.com.br\/index.php\/2024\/08\/13\/assistente-de-orcamento-palhoca-sc-17\/#article","isPartOf":{"@id":"https:\/\/www.vagasempregosc.com.br\/index.php\/2024\/08\/13\/assistente-de-orcamento-palhoca-sc-17\/"},"author":{"name":"Vagas Emprego SC","@id":"https:\/\/www.vagasempregosc.com.br\/#\/schema\/person\/e59ecb0cf33cc401d3b82548d1a9baa4"},"headline":"Assistente de Or\u00e7amento &#8211; Palho\u00e7a &#8211; SC","datePublished":"2024-08-13T20:00:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vagasempregosc.com.br\/index.php\/2024\/08\/13\/assistente-de-orcamento-palhoca-sc-17\/"},"wordCount":339,"publisher":{"@id":"https:\/\/www.vagasempregosc.com.br\/#organization"},"articleSection":["administra\u00e7\u00e3o geral","ensino m\u00e9dio","vagas diversas"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.vagasempregosc.com.br\/index.php\/2024\/08\/13\/assistente-de-orcamento-palhoca-sc-17\/","url":"https:\/\/www.vagasempregosc.com.br\/index.php\/2024\/08\/13\/assistente-de-orcamento-palhoca-sc-17\/","name":"Assistente de Or\u00e7amento - Palho\u00e7a - SC - Vagas Emprego SC","isPartOf":{"@id":"https:\/\/www.vagasempregosc.com.br\/#website"},"datePublished":"2024-08-13T20:00:41+00:00","breadcrumb":{"@id":"https:\/\/www.vagasempregosc.com.br\/index.php\/2024\/08\/13\/assistente-de-orcamento-palhoca-sc-17\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vagasempregosc.com.br\/index.php\/2024\/08\/13\/assistente-de-orcamento-palhoca-sc-17\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vagasempregosc.com.br\/index.php\/2024\/08\/13\/assistente-de-orcamento-palhoca-sc-17\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vagasempregosc.com.br\/"},{"@type":"ListItem","position":2,"name":"Assistente de Or\u00e7amento &#8211; Palho\u00e7a &#8211; SC"}]},{"@type":"WebSite","@id":"https:\/\/www.vagasempregosc.com.br\/#website","url":"https:\/\/www.vagasempregosc.com.br\/","name":"Vagas Emprego SC","description":"Vagas de emprego e est\u00e1gio em Santa Catarina","publisher":{"@id":"https:\/\/www.vagasempregosc.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vagasempregosc.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.vagasempregosc.com.br\/#organization","name":"Vagas Emprego SC","url":"https:\/\/www.vagasempregosc.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.vagasempregosc.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.vagasempregosc.com.br\/wp-content\/uploads\/2025\/05\/cropped-logo2015sc.jpg","contentUrl":"https:\/\/www.vagasempregosc.com.br\/wp-content\/uploads\/2025\/05\/cropped-logo2015sc.jpg","width":323,"height":89,"caption":"Vagas Emprego SC"},"image":{"@id":"https:\/\/www.vagasempregosc.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.vagasempregosc.com.br\/#\/schema\/person\/e59ecb0cf33cc401d3b82548d1a9baa4","name":"Vagas Emprego SC","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","caption":"Vagas Emprego SC"},"url":"https:\/\/www.vagasempregosc.com.br\/index.php\/author\/vagasemprego\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/39067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=39067"}],"version-history":[{"count":0,"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/39067\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=39067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=39067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=39067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}