{"id":41877,"date":"2025-06-12T09:00:10","date_gmt":"2025-06-12T12:00:10","guid":{"rendered":"https:\/\/www.vagasempregosc.com.br\/?p=41877"},"modified":"2025-06-11T16:08:31","modified_gmt":"2025-06-11T19:08:31","slug":"codigo-26757-assistente-financeiro-blumenau-sc","status":"publish","type":"post","link":"https:\/\/www.vagasempregosc.com.br\/index.php\/2025\/06\/12\/codigo-26757-assistente-financeiro-blumenau-sc\/","title":{"rendered":"C\u00f3digo: 26757 &#8211; Assistente Financeiro &#8211; Blumenau &#8211; SC"},"content":{"rendered":"<p style=\"text-align: justify;\">Requisitos:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Ensino Superior Completo ou Cursando<\/li>\n<li>Ter viv\u00eancia na fun\u00e7\u00e3o.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Atividades da fun\u00e7\u00e3o:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Controle de contas a pagar e receber, emiss\u00e3o de notas fiscais, controle do fluxo de caixa, concilia\u00e7\u00e3o banc\u00e1ria, negocia\u00e7\u00e3o com fornecedores e clientes, elabora\u00e7\u00e3o de relat\u00f3rios financeiros e an\u00e1lise de balan\u00e7os.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Jornada de trabalho:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Segunda a Sexta Feira das 08:30 \u00e0s 17:30<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Benef\u00edcios:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Vale transporte, aux\u00edlio alimenta\u00e7\u00e3o, plano de sa\u00fade e seguro de vida.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Cadastrar curr\u00edculo informando no assunto a vaga de interesse para o Link recrutarrh.com.br<br \/>\nMaiores informa\u00e7\u00f5es pelo fone (47) 3222-0102 \/ Vaga: 26757<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Requisitos: Ensino Superior Completo ou Cursando Ter viv\u00eancia na fun\u00e7\u00e3o. Atividades da fun\u00e7\u00e3o: Controle de contas a pagar e receber, emiss\u00e3o de notas fiscais, controle [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,14,15],"tags":[],"class_list":["post-41877","post","type-post","status-publish","format-standard","hentry","category-contabil-financeiro","category-ensino-superior-completo","category-ensino-superior-em-andamento-incompleto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f3digo: 26757 - Assistente Financeiro - Blumenau - SC - Vagas Emprego SC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vagasempregosc.com.br\/index.php\/2025\/06\/12\/codigo-26757-assistente-financeiro-blumenau-sc\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3digo: 26757 - Assistente Financeiro - Blumenau - SC - Vagas Emprego SC\" \/>\n<meta property=\"og:description\" content=\"Requisitos: Ensino Superior Completo ou Cursando Ter viv\u00eancia na fun\u00e7\u00e3o. Atividades da fun\u00e7\u00e3o: Controle de contas a pagar e receber, emiss\u00e3o de notas fiscais, controle [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vagasempregosc.com.br\/index.php\/2025\/06\/12\/codigo-26757-assistente-financeiro-blumenau-sc\/\" \/>\n<meta property=\"og:site_name\" content=\"Vagas Emprego SC\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-12T12:00:10+00:00\" \/>\n<meta name=\"author\" content=\"Vagas Emprego SC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vagas Emprego SC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2025\\\/06\\\/12\\\/codigo-26757-assistente-financeiro-blumenau-sc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2025\\\/06\\\/12\\\/codigo-26757-assistente-financeiro-blumenau-sc\\\/\"},\"author\":{\"name\":\"Vagas Emprego SC\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#\\\/schema\\\/person\\\/e59ecb0cf33cc401d3b82548d1a9baa4\"},\"headline\":\"C\u00f3digo: 26757 &#8211; Assistente Financeiro &#8211; Blumenau &#8211; SC\",\"datePublished\":\"2025-06-12T12:00:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2025\\\/06\\\/12\\\/codigo-26757-assistente-financeiro-blumenau-sc\\\/\"},\"wordCount\":112,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#organization\"},\"articleSection\":[\"cont\u00e1bil \\\/ financeiro\",\"ensino superior\",\"ensino superior incompleto\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2025\\\/06\\\/12\\\/codigo-26757-assistente-financeiro-blumenau-sc\\\/\",\"url\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2025\\\/06\\\/12\\\/codigo-26757-assistente-financeiro-blumenau-sc\\\/\",\"name\":\"C\u00f3digo: 26757 - Assistente Financeiro - Blumenau - SC - Vagas Emprego SC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#website\"},\"datePublished\":\"2025-06-12T12:00:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2025\\\/06\\\/12\\\/codigo-26757-assistente-financeiro-blumenau-sc\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2025\\\/06\\\/12\\\/codigo-26757-assistente-financeiro-blumenau-sc\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2025\\\/06\\\/12\\\/codigo-26757-assistente-financeiro-blumenau-sc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3digo: 26757 &#8211; Assistente Financeiro &#8211; Blumenau &#8211; SC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#website\",\"url\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/\",\"name\":\"Vagas Emprego SC\",\"description\":\"Vagas de emprego e est\u00e1gio em Santa Catarina\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#organization\",\"name\":\"Vagas Emprego SC\",\"url\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-logo2015sc.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-logo2015sc.jpg\",\"width\":323,\"height\":89,\"caption\":\"Vagas Emprego SC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#\\\/schema\\\/person\\\/e59ecb0cf33cc401d3b82548d1a9baa4\",\"name\":\"Vagas Emprego SC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"caption\":\"Vagas Emprego SC\"},\"url\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/author\\\/vagasemprego\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3digo: 26757 - Assistente Financeiro - Blumenau - SC - Vagas Emprego SC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vagasempregosc.com.br\/index.php\/2025\/06\/12\/codigo-26757-assistente-financeiro-blumenau-sc\/","og_locale":"pt_BR","og_type":"article","og_title":"C\u00f3digo: 26757 - Assistente Financeiro - Blumenau - SC - Vagas Emprego SC","og_description":"Requisitos: Ensino Superior Completo ou Cursando Ter viv\u00eancia na fun\u00e7\u00e3o. Atividades da fun\u00e7\u00e3o: Controle de contas a pagar e receber, emiss\u00e3o de notas fiscais, controle [...]","og_url":"https:\/\/www.vagasempregosc.com.br\/index.php\/2025\/06\/12\/codigo-26757-assistente-financeiro-blumenau-sc\/","og_site_name":"Vagas Emprego SC","article_published_time":"2025-06-12T12:00:10+00:00","author":"Vagas Emprego SC","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Vagas Emprego SC","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vagasempregosc.com.br\/index.php\/2025\/06\/12\/codigo-26757-assistente-financeiro-blumenau-sc\/#article","isPartOf":{"@id":"https:\/\/www.vagasempregosc.com.br\/index.php\/2025\/06\/12\/codigo-26757-assistente-financeiro-blumenau-sc\/"},"author":{"name":"Vagas Emprego SC","@id":"https:\/\/www.vagasempregosc.com.br\/#\/schema\/person\/e59ecb0cf33cc401d3b82548d1a9baa4"},"headline":"C\u00f3digo: 26757 &#8211; Assistente Financeiro &#8211; Blumenau &#8211; SC","datePublished":"2025-06-12T12:00:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vagasempregosc.com.br\/index.php\/2025\/06\/12\/codigo-26757-assistente-financeiro-blumenau-sc\/"},"wordCount":112,"publisher":{"@id":"https:\/\/www.vagasempregosc.com.br\/#organization"},"articleSection":["cont\u00e1bil \/ financeiro","ensino superior","ensino superior incompleto"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.vagasempregosc.com.br\/index.php\/2025\/06\/12\/codigo-26757-assistente-financeiro-blumenau-sc\/","url":"https:\/\/www.vagasempregosc.com.br\/index.php\/2025\/06\/12\/codigo-26757-assistente-financeiro-blumenau-sc\/","name":"C\u00f3digo: 26757 - Assistente Financeiro - Blumenau - SC - Vagas Emprego SC","isPartOf":{"@id":"https:\/\/www.vagasempregosc.com.br\/#website"},"datePublished":"2025-06-12T12:00:10+00:00","breadcrumb":{"@id":"https:\/\/www.vagasempregosc.com.br\/index.php\/2025\/06\/12\/codigo-26757-assistente-financeiro-blumenau-sc\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vagasempregosc.com.br\/index.php\/2025\/06\/12\/codigo-26757-assistente-financeiro-blumenau-sc\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vagasempregosc.com.br\/index.php\/2025\/06\/12\/codigo-26757-assistente-financeiro-blumenau-sc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vagasempregosc.com.br\/"},{"@type":"ListItem","position":2,"name":"C\u00f3digo: 26757 &#8211; Assistente Financeiro &#8211; Blumenau &#8211; SC"}]},{"@type":"WebSite","@id":"https:\/\/www.vagasempregosc.com.br\/#website","url":"https:\/\/www.vagasempregosc.com.br\/","name":"Vagas Emprego SC","description":"Vagas de emprego e est\u00e1gio em Santa Catarina","publisher":{"@id":"https:\/\/www.vagasempregosc.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vagasempregosc.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.vagasempregosc.com.br\/#organization","name":"Vagas Emprego SC","url":"https:\/\/www.vagasempregosc.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.vagasempregosc.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.vagasempregosc.com.br\/wp-content\/uploads\/2025\/05\/cropped-logo2015sc.jpg","contentUrl":"https:\/\/www.vagasempregosc.com.br\/wp-content\/uploads\/2025\/05\/cropped-logo2015sc.jpg","width":323,"height":89,"caption":"Vagas Emprego SC"},"image":{"@id":"https:\/\/www.vagasempregosc.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.vagasempregosc.com.br\/#\/schema\/person\/e59ecb0cf33cc401d3b82548d1a9baa4","name":"Vagas Emprego SC","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","caption":"Vagas Emprego SC"},"url":"https:\/\/www.vagasempregosc.com.br\/index.php\/author\/vagasemprego\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=41877"}],"version-history":[{"count":1,"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41877\/revisions"}],"predecessor-version":[{"id":41878,"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41877\/revisions\/41878"}],"wp:attachment":[{"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=41877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=41877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=41877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}