{"id":43220,"date":"2025-10-23T11:00:03","date_gmt":"2025-10-23T14:00:03","guid":{"rendered":"https:\/\/www.vagasempregosc.com.br\/?p=43220"},"modified":"2025-10-22T19:29:05","modified_gmt":"2025-10-22T22:29:05","slug":"auxiliar-de-logistica-navegantes-sc","status":"publish","type":"post","link":"https:\/\/www.vagasempregosc.com.br\/index.php\/2025\/10\/23\/auxiliar-de-logistica-navegantes-sc\/","title":{"rendered":"Auxiliar de Log\u00edstica &#8211; Navegantes &#8211; SC"},"content":{"rendered":"<p style=\"text-align: justify;\">Atividades e Responsabilidades:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Realizar o recebimento, confer\u00eancia e armazenamento de produtos;<\/li>\n<li>Separar, embalar e montar pedidos para distribui\u00e7\u00e3o;<\/li>\n<li>Controlar o estoque e processar as devolu\u00e7\u00f5es de mercadorias;<\/li>\n<li>Realizar invent\u00e1rios peri\u00f3dicos;<\/li>\n<li>Apoiar no processo de expedi\u00e7\u00e3o de produtos e na roteiriza\u00e7\u00e3o de entregas;<\/li>\n<li>Manter o ambiente de trabalho limpo e organizado;<\/li>\n<li>Cumprir com os padr\u00f5es de seguran\u00e7a estabelecidos;<\/li>\n<li>Realizar atividades administrativas b\u00e1sicas relacionadas \u00e0 \u00e1rea.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Requisitos:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Ensino m\u00e9dio completo;<\/li>\n<li>Experi\u00eancia anterior na \u00e1rea de log\u00edstica ser\u00e1 um diferencial;<\/li>\n<li>Boa comunica\u00e7\u00e3o;<\/li>\n<li>Disponibilidade para trabalhar em hor\u00e1rio comercial ( Segunda \u00e0 sexta)<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Jornada de Trabalho:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Segunda a Sexta Feira das 08:00 \u00e1s 18:00.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Benef\u00edcios:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Plano de Sa\u00fade<\/li>\n<li>Plano Odontol\u00f3gico<\/li>\n<li>Vale refei\u00e7\u00e3o ou alimenta\u00e7\u00e3o<\/li>\n<li>Transporte fretado<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Data m\u00e1xima para envio de curr\u00edculos: 30-10-2025<\/p>\n<p style=\"text-align: justify;\">Enviar curr\u00edculo informando no assunto do e-mail a vaga de interesse para <a href=\"mailto:marcelaantunes@frigelar.com.br\">marcelaantunes@frigelar.com.br<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Atividades e Responsabilidades: Realizar o recebimento, confer\u00eancia e armazenamento de produtos; Separar, embalar e montar pedidos para distribui\u00e7\u00e3o; Controlar o estoque e processar as devolu\u00e7\u00f5es [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,9],"tags":[],"class_list":["post-43220","post","type-post","status-publish","format-standard","hentry","category-ensino-medio-completo","category-logistica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Auxiliar de Log\u00edstica - Navegantes - SC - Vagas Emprego SC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vagasempregosc.com.br\/index.php\/2025\/10\/23\/auxiliar-de-logistica-navegantes-sc\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Auxiliar de Log\u00edstica - Navegantes - SC - Vagas Emprego SC\" \/>\n<meta property=\"og:description\" content=\"Atividades e Responsabilidades: Realizar o recebimento, confer\u00eancia e armazenamento de produtos; Separar, embalar e montar pedidos para distribui\u00e7\u00e3o; Controlar o estoque e processar as devolu\u00e7\u00f5es [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vagasempregosc.com.br\/index.php\/2025\/10\/23\/auxiliar-de-logistica-navegantes-sc\/\" \/>\n<meta property=\"og:site_name\" content=\"Vagas Emprego SC\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-23T14:00:03+00:00\" \/>\n<meta name=\"author\" content=\"Vagas Emprego SC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vagas Emprego SC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2025\\\/10\\\/23\\\/auxiliar-de-logistica-navegantes-sc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2025\\\/10\\\/23\\\/auxiliar-de-logistica-navegantes-sc\\\/\"},\"author\":{\"name\":\"Vagas Emprego SC\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#\\\/schema\\\/person\\\/e59ecb0cf33cc401d3b82548d1a9baa4\"},\"headline\":\"Auxiliar de Log\u00edstica &#8211; Navegantes &#8211; SC\",\"datePublished\":\"2025-10-23T14:00:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2025\\\/10\\\/23\\\/auxiliar-de-logistica-navegantes-sc\\\/\"},\"wordCount\":162,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#organization\"},\"articleSection\":[\"ensino m\u00e9dio\",\"log\u00edstica \\\/ distribui\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2025\\\/10\\\/23\\\/auxiliar-de-logistica-navegantes-sc\\\/\",\"url\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2025\\\/10\\\/23\\\/auxiliar-de-logistica-navegantes-sc\\\/\",\"name\":\"Auxiliar de Log\u00edstica - Navegantes - SC - Vagas Emprego SC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#website\"},\"datePublished\":\"2025-10-23T14:00:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2025\\\/10\\\/23\\\/auxiliar-de-logistica-navegantes-sc\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2025\\\/10\\\/23\\\/auxiliar-de-logistica-navegantes-sc\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/2025\\\/10\\\/23\\\/auxiliar-de-logistica-navegantes-sc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Auxiliar de Log\u00edstica &#8211; Navegantes &#8211; SC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#website\",\"url\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/\",\"name\":\"Vagas Emprego SC\",\"description\":\"Vagas de emprego e est\u00e1gio em Santa Catarina\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#organization\",\"name\":\"Vagas Emprego SC\",\"url\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-logo2015sc.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-logo2015sc.jpg\",\"width\":323,\"height\":89,\"caption\":\"Vagas Emprego SC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/#\\\/schema\\\/person\\\/e59ecb0cf33cc401d3b82548d1a9baa4\",\"name\":\"Vagas Emprego SC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"caption\":\"Vagas Emprego SC\"},\"url\":\"https:\\\/\\\/www.vagasempregosc.com.br\\\/index.php\\\/author\\\/vagasemprego\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Auxiliar de Log\u00edstica - Navegantes - SC - Vagas Emprego SC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vagasempregosc.com.br\/index.php\/2025\/10\/23\/auxiliar-de-logistica-navegantes-sc\/","og_locale":"pt_BR","og_type":"article","og_title":"Auxiliar de Log\u00edstica - Navegantes - SC - Vagas Emprego SC","og_description":"Atividades e Responsabilidades: Realizar o recebimento, confer\u00eancia e armazenamento de produtos; Separar, embalar e montar pedidos para distribui\u00e7\u00e3o; Controlar o estoque e processar as devolu\u00e7\u00f5es [...]","og_url":"https:\/\/www.vagasempregosc.com.br\/index.php\/2025\/10\/23\/auxiliar-de-logistica-navegantes-sc\/","og_site_name":"Vagas Emprego SC","article_published_time":"2025-10-23T14:00:03+00:00","author":"Vagas Emprego SC","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Vagas Emprego SC","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vagasempregosc.com.br\/index.php\/2025\/10\/23\/auxiliar-de-logistica-navegantes-sc\/#article","isPartOf":{"@id":"https:\/\/www.vagasempregosc.com.br\/index.php\/2025\/10\/23\/auxiliar-de-logistica-navegantes-sc\/"},"author":{"name":"Vagas Emprego SC","@id":"https:\/\/www.vagasempregosc.com.br\/#\/schema\/person\/e59ecb0cf33cc401d3b82548d1a9baa4"},"headline":"Auxiliar de Log\u00edstica &#8211; Navegantes &#8211; SC","datePublished":"2025-10-23T14:00:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vagasempregosc.com.br\/index.php\/2025\/10\/23\/auxiliar-de-logistica-navegantes-sc\/"},"wordCount":162,"publisher":{"@id":"https:\/\/www.vagasempregosc.com.br\/#organization"},"articleSection":["ensino m\u00e9dio","log\u00edstica \/ distribui\u00e7\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.vagasempregosc.com.br\/index.php\/2025\/10\/23\/auxiliar-de-logistica-navegantes-sc\/","url":"https:\/\/www.vagasempregosc.com.br\/index.php\/2025\/10\/23\/auxiliar-de-logistica-navegantes-sc\/","name":"Auxiliar de Log\u00edstica - Navegantes - SC - Vagas Emprego SC","isPartOf":{"@id":"https:\/\/www.vagasempregosc.com.br\/#website"},"datePublished":"2025-10-23T14:00:03+00:00","breadcrumb":{"@id":"https:\/\/www.vagasempregosc.com.br\/index.php\/2025\/10\/23\/auxiliar-de-logistica-navegantes-sc\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vagasempregosc.com.br\/index.php\/2025\/10\/23\/auxiliar-de-logistica-navegantes-sc\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vagasempregosc.com.br\/index.php\/2025\/10\/23\/auxiliar-de-logistica-navegantes-sc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vagasempregosc.com.br\/"},{"@type":"ListItem","position":2,"name":"Auxiliar de Log\u00edstica &#8211; Navegantes &#8211; SC"}]},{"@type":"WebSite","@id":"https:\/\/www.vagasempregosc.com.br\/#website","url":"https:\/\/www.vagasempregosc.com.br\/","name":"Vagas Emprego SC","description":"Vagas de emprego e est\u00e1gio em Santa Catarina","publisher":{"@id":"https:\/\/www.vagasempregosc.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vagasempregosc.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.vagasempregosc.com.br\/#organization","name":"Vagas Emprego SC","url":"https:\/\/www.vagasempregosc.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.vagasempregosc.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.vagasempregosc.com.br\/wp-content\/uploads\/2025\/05\/cropped-logo2015sc.jpg","contentUrl":"https:\/\/www.vagasempregosc.com.br\/wp-content\/uploads\/2025\/05\/cropped-logo2015sc.jpg","width":323,"height":89,"caption":"Vagas Emprego SC"},"image":{"@id":"https:\/\/www.vagasempregosc.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.vagasempregosc.com.br\/#\/schema\/person\/e59ecb0cf33cc401d3b82548d1a9baa4","name":"Vagas Emprego SC","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","caption":"Vagas Emprego SC"},"url":"https:\/\/www.vagasempregosc.com.br\/index.php\/author\/vagasemprego\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/43220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=43220"}],"version-history":[{"count":1,"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/43220\/revisions"}],"predecessor-version":[{"id":43221,"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/43220\/revisions\/43221"}],"wp:attachment":[{"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=43220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=43220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vagasempregosc.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=43220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}